{"id":8,"count":2,"description":"","link":"http:\/\/creativewatersart.com\/blog\/category\/portfolio\/","name":"portfolio","slug":"portfolio","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/creativewatersart.com\/blog\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/creativewatersart.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/creativewatersart.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/creativewatersart.com\/blog\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}